{"id":24385,"date":"2025-03-18T13:07:27","date_gmt":"2025-03-18T12:07:27","guid":{"rendered":"https:\/\/self-publishing.com\/?post_type=product&#038;p=24385"},"modified":"2025-03-18T13:07:29","modified_gmt":"2025-03-18T12:07:29","slug":"hinter-dem-spiegel-geheime-seelen","status":"publish","type":"product","link":"https:\/\/self-publishing.com\/es\/producto\/tras-el-espejo-almas-secretas\/","title":{"rendered":"Detr\u00e1s del espejo: Almas secretas"},"content":{"rendered":"<p>\u00a1La aventura contin\u00faa! Despu\u00e9s de que Isabel haya liberado Arandeen de la malvada Reina Lydia, lo \u00fanico que desea es instalarse en la universidad y ser feliz con Nikolas. Pero una nueva tarea ya la est\u00e1 esperando para llevarla de vuelta al mundo detr\u00e1s del espejo.<br \/>\n\u00bfSer\u00e1 capaz de superar todos los obst\u00e1culos y salvar a sus amigos y al amor de su vida?<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00a1La aventura contin\u00faa! Despu\u00e9s de que Isabel haya liberado Arandeen de la malvada Reina Lydia, lo \u00fanico que desea es instalarse en la universidad y ser feliz con Nikolas. Pero una nueva tarea la espera para llevarla de vuelta al mundo detr\u00e1s del espejo. \u00bfSuperar\u00e1 todos los obst\u00e1culos, encontrar\u00e1 a sus amigos y [...]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"https:\/\/self-publishing.com\/es\/producto\/tras-el-espejo-almas-secretas\/\">Leer m\u00e1s...<\/a><\/p>","protected":false},"featured_media":24383,"template":"","meta":{"footnotes":""},"product_brand":[],"product_cat":[64],"product_tag":[2139,383],"class_list":{"0":"post-24385","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-fantasy","7":"product_tag-fantasy-en","8":"product_tag-jugendbuch","10":"first","11":"instock","12":"downloadable","13":"virtual","14":"taxable","15":"purchasable","16":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/self-publishing.com\/es\/wp-json\/wp\/v2\/product\/24385","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/self-publishing.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/self-publishing.com\/es\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/self-publishing.com\/es\/wp-json\/wp\/v2\/product\/24385\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/self-publishing.com\/es\/wp-json\/wp\/v2\/media\/24383"}],"wp:attachment":[{"href":"https:\/\/self-publishing.com\/es\/wp-json\/wp\/v2\/media?parent=24385"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/self-publishing.com\/es\/wp-json\/wp\/v2\/product_brand?post=24385"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/self-publishing.com\/es\/wp-json\/wp\/v2\/product_cat?post=24385"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/self-publishing.com\/es\/wp-json\/wp\/v2\/product_tag?post=24385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}