{"id":24402,"date":"2025-03-18T12:55:28","date_gmt":"2025-03-18T11:55:28","guid":{"rendered":"https:\/\/self-publishing.com\/?post_type=product&#038;p=24402"},"modified":"2025-03-18T12:55:30","modified_gmt":"2025-03-18T11:55:30","slug":"heilendes-bewusstsein","status":"publish","type":"product","link":"https:\/\/self-publishing.com\/es\/producto\/conciencia-curativa\/","title":{"rendered":"Conciencia curativa"},"content":{"rendered":"<p>El Dr. Brucker naci\u00f3 en Tirschenreuth\/Baviera en 1957.<\/p>\n<p>Tras dejar la escuela, estudi\u00f3 medicina. Tras el examen de Estado, se especializ\u00f3 en psiquiatr\u00eda y neurolog\u00eda. Desde hace 20 a\u00f1os trabaja en su propia consulta.<\/p>\n<p>Tras sus dos primeros libros \"La vida despu\u00e9s de la muerte - lo que ya podemos saber hoy\" y \"Un vistazo al cielo\", ahora centra su atenci\u00f3n en la conciencia. Se trata de las preguntas<\/p>\n<p>\u00bfQu\u00e9 cura?<\/p>\n<p>\u00bfQu\u00e9 es nuestra conciencia?<\/p>\n<p>\u00bfC\u00f3mo explicar las curaciones milagrosas?<\/p>","protected":false},"excerpt":{"rendered":"<p>Dr. med. Brucker wurde 1957 in Tirschenreuth\/Bayern geboren. Nach dem Abitur studierte er Medizin. Nach dem Staatsexamen spezialisierte er sich zum Facharzt f\u00fcr Psychiatrie und Neurologie. Seit 20 Jahren ist er in einer eigenen Praxis t\u00e4tig. Nach seinen ersten beiden B\u00fcchern \u00bbLeben nach dem Tod \u2013 was wir heute schon wissen k\u00f6nnen\u00ab und \u00bbBlick in [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"https:\/\/self-publishing.com\/es\/producto\/conciencia-curativa\/\">Leer m\u00e1s...<\/a><\/p>","protected":false},"featured_media":24400,"template":"","meta":{"footnotes":""},"product_brand":[],"product_cat":[1326,2810],"product_tag":[1596],"class_list":{"0":"post-24402","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-alle-buecher","7":"product_cat-fachbuecher","8":"product_tag-heilung","10":"first","11":"instock","12":"downloadable","13":"virtual","14":"taxable","15":"purchasable","16":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/self-publishing.com\/es\/wp-json\/wp\/v2\/product\/24402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/self-publishing.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/self-publishing.com\/es\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/self-publishing.com\/es\/wp-json\/wp\/v2\/product\/24402\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/self-publishing.com\/es\/wp-json\/wp\/v2\/media\/24400"}],"wp:attachment":[{"href":"https:\/\/self-publishing.com\/es\/wp-json\/wp\/v2\/media?parent=24402"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/self-publishing.com\/es\/wp-json\/wp\/v2\/product_brand?post=24402"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/self-publishing.com\/es\/wp-json\/wp\/v2\/product_cat?post=24402"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/self-publishing.com\/es\/wp-json\/wp\/v2\/product_tag?post=24402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}