{"id":7022,"date":"2019-03-06T14:34:48","date_gmt":"2019-03-06T13:34:48","guid":{"rendered":"https:\/\/selfpubcom.wpengine.com\/?post_type=product&#038;p=7022"},"modified":"2025-02-25T12:06:52","modified_gmt":"2025-02-25T11:06:52","slug":"have-i-seen-you-before-baby","status":"publish","type":"product","link":"https:\/\/self-publishing.com\/es\/producto\/te-he-visto-antes-nena\/","title":{"rendered":"\u00bfTe he visto antes, cari\u00f1o? Historias de LBM Parte 3"},"content":{"rendered":"<p>Ahora que Mirjam se ha convertido en la nueva imagen de la marca l\u00edder de comida para gatos Schulze-Rank, se esfuerza por compaginar todos sus compromisos. Va de cita en cita para no decepcionar a nadie. Pero su vida privada queda relegada a un segundo plano. Hasta que un d\u00eda el sexy Lucas se cruza en su camino y la confunde por completo.<\/p>\n<p>&nbsp;<\/p>\n<p>Estaba tan concentrada que casi atropella al gigante que de repente se interpuso en su camino. \"\u00a1Uy, jovencita, cuidado!\". Mirjam ech\u00f3 la cabeza hacia atr\u00e1s y busc\u00f3 la cara de la pared humana con la que acababa de chocar. \"\u00a1Lo siento, no era mi intenci\u00f3n!\", consigui\u00f3 decir. Tard\u00f3 unos segundos en distinguir la cara porque el sol la cegaba. Le gust\u00f3 mucho lo que vio. El pelo casta\u00f1o y despeinado y una barba de tres d\u00edas bien cuidada le sonre\u00edan. Por desgracia, no pudo verle los ojos porque, como ella, llevaba gafas de sol. \"\u00a1No hay problema!\" Su voz era profunda y c\u00e1lida. Un peque\u00f1o escalofr\u00edo la recorri\u00f3. Su sonrisa se intensific\u00f3 y lade\u00f3 ligeramente la cabeza, esperando su reacci\u00f3n. OMG, lo estoy mirando, se dio cuenta y despert\u00f3 de su estupor. \"Perdona, no te hab\u00eda visto\", volvi\u00f3 a decir e intent\u00f3 dar un paso a un lado, pero aun as\u00ed otra persona choc\u00f3 con ella. Maldita sea, ella estaba en medio de una multitud de personas reunidas alrededor de un carrito de cerveza tratando de conseguir una bebida. \"De nuevo, no hay ning\u00fan problema. Es que est\u00e1 s\u00faper lleno y no pasa nada\". Mirjam le sonri\u00f3 agradecida. \"Lucas\", dijo su interlocutor y le tendi\u00f3 la mano derecha. \"\u00bfEst\u00e1s aqu\u00ed solo?\" \"\u00a1Mirjam, hola! No, estoy buscando a mis amigos. Deber\u00edan estar m\u00e1s atr\u00e1s, junto al estanque\". \"\u00bfTe abro camino?\", pregunt\u00f3 Lucas. A\u00fan llevaba las gafas puestas, lo que la molest\u00f3. Ella quer\u00eda ver sus ojos. No es que se hubiera quitado los suyos, pero a\u00fan as\u00ed. \"Er, no, est\u00e1 bien. Puedo arregl\u00e1rmelas\". \"Vale. Me resultas familiar. \u00bfNos conocemos de alguna manera?\" \"Oh bueno, esa es una frase original...\" respondi\u00f3 ella y ahora estaba realmente molesta. \u00bfPor qu\u00e9 estos tipos siempre ten\u00edan que ser tan est\u00fapidos? Un simple, fue agradable, tal vez tomemos una cerveza juntos alguna vez, ser\u00eda suficiente. Pero \u00e9l se ech\u00f3 a re\u00edr, muy alto y a carcajadas: \"No, cari\u00f1o, no me refer\u00eda a eso. En serio, \u00bferes famosa o algo as\u00ed? Te conozco\". \u00bfCari\u00f1o? Seguro que no hablaba en serio... \u00bfQu\u00e9 se cre\u00eda que estaba haciendo este hombre?<\/p>","protected":false},"excerpt":{"rendered":"<p>Ahora que Mirjam se ha convertido en la nueva imagen de la marca l\u00edder de comida para gatos Schulze-Rank, se esfuerza por compaginar todos sus compromisos. Va de cita en cita para no decepcionar a nadie. Pero su vida privada queda relegada a un segundo plano. Hasta que un d\u00eda, el sexy Lucas se cruza en su [...]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"https:\/\/self-publishing.com\/es\/producto\/te-he-visto-antes-nena\/\">Leer m\u00e1s...<\/a><\/p>","protected":false},"featured_media":7019,"template":"","meta":{"footnotes":""},"product_brand":[],"product_cat":[1326,2815],"product_tag":[2153,1006,2131],"class_list":{"0":"post-7022","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-alle-buecher","7":"product_cat-liebesromane","8":"product_tag-lbm-en","9":"product_tag-lbm-stories","10":"product_tag-marilu-en","12":"first","13":"instock","14":"downloadable","15":"virtual","16":"taxable","17":"purchasable","18":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/self-publishing.com\/es\/wp-json\/wp\/v2\/product\/7022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/self-publishing.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/self-publishing.com\/es\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/self-publishing.com\/es\/wp-json\/wp\/v2\/product\/7022\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/self-publishing.com\/es\/wp-json\/wp\/v2\/media\/7019"}],"wp:attachment":[{"href":"https:\/\/self-publishing.com\/es\/wp-json\/wp\/v2\/media?parent=7022"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/self-publishing.com\/es\/wp-json\/wp\/v2\/product_brand?post=7022"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/self-publishing.com\/es\/wp-json\/wp\/v2\/product_cat?post=7022"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/self-publishing.com\/es\/wp-json\/wp\/v2\/product_tag?post=7022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}